{"id":4468,"date":"2020-01-06T10:13:21","date_gmt":"2020-01-06T01:13:21","guid":{"rendered":"https:\/\/opop.tsukuba.ac.jp\/?p=4468"},"modified":"2020-01-06T10:18:26","modified_gmt":"2020-01-06T01:18:26","slug":"%e9%99%84%e5%b1%9e%e8%a6%96%e8%a6%9a%e7%89%b9%e5%88%a5%e6%94%af%e6%8f%b4%e5%ad%a6%e6%a0%a1%e5%87%ba%e8%ba%ab%e3%81%ae%e6%b2%b3%e5%90%88%e7%b4%94%e4%b8%80%e6%b0%8f%e3%81%8c%e3%80%81jpc%e5%a7%94","status":"publish","type":"post","link":"https:\/\/opop.tsukuba.ac.jp\/en\/2020\/01\/06\/%e9%99%84%e5%b1%9e%e8%a6%96%e8%a6%9a%e7%89%b9%e5%88%a5%e6%94%af%e6%8f%b4%e5%ad%a6%e6%a0%a1%e5%87%ba%e8%ba%ab%e3%81%ae%e6%b2%b3%e5%90%88%e7%b4%94%e4%b8%80%e6%b0%8f%e3%81%8c%e3%80%81jpc%e5%a7%94\/","title":{"rendered":"Mr. KAWAI Junichi was appointed the chairman of the Japanese Paralympic Committee"},"content":{"rendered":"<p><\/p>\n<p>Mr. KAWAI Junichi was appointed the chairman of the Japanese Paralympic Committee (JPC) on January 1st, 2020.<\/p>\n<p>&nbsp;<\/p>\n<p>He graduated from Special Needs School for the Visually Impaired, University of Tsukuba.<\/p>\n<p>He participated in the Paralympic Games six times (Barcelona in 1992, Atlanta in 1996, Sydney in 2000, Athens in 2004, Beijing in 2008, London in 2012). He won twenty one medals including five gold medals in swimming.<\/p>\n<p>&nbsp;<\/p>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Mr. KAWAI Junichi was appointed the chairman of the Japanese Paralympic Committee (JPC) on January 1st, 2020.  [&hellip;]<\/p>\n","protected":false},"author":111,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-4468","post","type-post","status-publish","format-standard","hentry","category-news"],"jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9qRTD-1a4","jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/opop.tsukuba.ac.jp\/en\/wp-json\/wp\/v2\/posts\/4468","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/opop.tsukuba.ac.jp\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/opop.tsukuba.ac.jp\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/opop.tsukuba.ac.jp\/en\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/opop.tsukuba.ac.jp\/en\/wp-json\/wp\/v2\/comments?post=4468"}],"version-history":[{"count":11,"href":"https:\/\/opop.tsukuba.ac.jp\/en\/wp-json\/wp\/v2\/posts\/4468\/revisions"}],"predecessor-version":[{"id":4503,"href":"https:\/\/opop.tsukuba.ac.jp\/en\/wp-json\/wp\/v2\/posts\/4468\/revisions\/4503"}],"wp:attachment":[{"href":"https:\/\/opop.tsukuba.ac.jp\/en\/wp-json\/wp\/v2\/media?parent=4468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/opop.tsukuba.ac.jp\/en\/wp-json\/wp\/v2\/categories?post=4468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/opop.tsukuba.ac.jp\/en\/wp-json\/wp\/v2\/tags?post=4468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}